{"id":70023163,"date":"2023-04-21T10:19:26","date_gmt":"2023-04-21T10:19:26","guid":{"rendered":"https:\/\/www.vetkintape.com\/de-de\/?post_type=product&#038;p=70023163"},"modified":"2025-05-06T08:37:07","modified_gmt":"2025-05-06T08:37:07","slug":"perdetaping-handbuch","status":"publish","type":"product","link":"https:\/\/vetkintape.ignito.nl\/de\/kinesiotape-bucher-tiere\/perdetaping-handbuch\/","title":{"rendered":"Taping Handbuch f\u00fcr Pferde"},"content":{"rendered":"<div class=\"row\">\n<div class=\"col-xs-12\">\n<p>Die \u00fcberarbeitete Ausgabe eines Buches von Renate Ettl ist nun verf\u00fcgbar und enth\u00e4lt ein umfangreiches Nachschlagewerk zu den <strong>Handgriffen, Anlagetechniken und Therapiem\u00f6glichkeiten des Kinesiologischen Tapings am Pferd<\/strong>, einschlie\u00dflich des VetkinTapes. Die Beschreibung der spezifischen Beschwerden und ihre nebenwirkungsfreie Behandlung sowie die Diagnosestellung vor dem Tapen werden detailliert und anschaulich anhand von vielen Bildern erl\u00e4utert. Das Buch bietet eine schrittweise Anleitung zum Erlernen der Grundlagen des Tapens wie Narben-, Muskel- und B\u00e4ndertapes sowie der Anlage von Tapes bei spezifischen Beschwerden. Es ist ein unverzichtbares Werkzeug f\u00fcr alle Pferdetherapeuten, die die Techniken des Kinesiologischen Tapings anwenden m\u00f6chten.<\/p>\n<p>VetkinTape ist in drei Gr\u00f6\u00dfen erh\u00e4ltlich und wurde speziell f\u00fcr den Tierarztmarkt entwickelt. Es handelt sich um ein sicheres, latexfreies Produkt, das mit einer starken Acrylklebeschicht ausgestattet ist, die eine bessere Haftung auf dem Fell des Tieres gew\u00e4hrleistet (+25% h\u00f6here Klebkraft). Aufgrund der starken Haftung bleibt das Klebeband fest auf der Haut des Tieres haften.<\/p>\n<p>Das elastische Klebeband bietet Halt, ohne die Bewegung einzuschr\u00e4nken, optimiert die Bewegung und lindert Schmerzen. Medical Tapen kann zur Unterst\u00fctzung der Physiotherapie oder als eigenst\u00e4ndige Behandlungsmethode verwendet werden. Es bietet Linderung f\u00fcr schmerzhafte Muskeln und \/ oder Gelenke, Haltungsprobleme oder wenn Pferde Probleme in ihrem Gang oder Lauf haben. <\/p>\n<p><strong>Dieses Handbuch bietet eine schrittweise Einf\u00fchrung in die verschiedenen Anwendungsm\u00f6glichkeiten von VetkinTape.<\/strong><\/p>\n<ul>\n<li>Ratschl\u00e4ge f\u00fcr eine gr\u00fcndliche Anamnese mit Ganganalyse, Palpation und spezifischen Tests, um die Probleme zu identifizieren.<\/li>\n<li>Anweisungen zum Anbringen von VetkinTape, damit f\u00fcr jedes Pferd ein Behandlungsplan erstellt werden kann.<\/li>\n<li>Tapeanwendungen bei mehr als 50 Krankheitsf\u00e4lle werden genau beschrieben.<\/li>\n<li>Die sch\u00f6nen Bilder machen es einfach, jede Tapeanwendung in der Praxis Schritt- f\u00fcr- Schritt anzuwenden.<\/li>\n<\/ul>\n<p><strong>Handbuch &#8220;kinesiotaping beim Pferd&#8220;:<\/strong><\/p>\n<ul>\n<li>ISBN \/ EAN 978-3-13-243117-1\u00b7<\/li>\n<li>Autor: Renate Ettl\u00b7<\/li>\n<li>Illustrator: Jeanne Kloepfer\u00b7<\/li>\n<li>Medical Taping Handbuch mit 276 Fotos (Vollfarbe)\u00b7<\/li>\n<li>Anzahl der Seiten: 224\u00b7<\/li>\n<li>Gr\u00f6\u00dfe: 27,5 x 19,5 x 1,6 cm\u00b7<\/li>\n<li>Deutscher Sprache (auch in Englisch erh\u00e4ltlich)<\/li>\n<\/ul>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Das <strong>umfangreiche Handbuch f\u00fcr Veterin\u00e4rtherapeuten zur Anwendung von VetkinTape<\/strong> wurde \u00fcberarbeitet und enth\u00e4lt nun Schritt-f\u00fcr-Schritt-Anleitungen f\u00fcr die grundlegenden Techniken des kinesiologischen Tapings bei Pferden. Dar\u00fcber hinaus werden mehr als 50 Krankheitsf\u00e4lle vorgestellt, um die Anwendungen und Behandlungstechniken zu veranschaulichen.<\/p>\n","protected":false},"featured_media":70023165,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[51],"product_tag":[],"class_list":["post-70023163","product","type-product","status-publish","has-post-thumbnail","product_cat-kinesiotape-bucher-tiere","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Taping Handbuch f\u00fcr Pferde | VetkinTape\u00ae DE Deutschland<\/title>\n<meta name=\"description\" content=\"Pferdetaping Handbuch von Renate Ettl (Deutsch) \u2714 Vertraut werden mit den wichtigsten Anlagemethoden und Therapiem\u00f6glichkeiten mit VetkinTape\u00ae\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vetkintape.com\/de\/kinesiotape-bucher-tiere\/perdetaping-handbuch\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Taping Handbuch f\u00fcr Pferde | VetkinTape\u00ae DE Deutschland\" \/>\n<meta property=\"og:description\" content=\"Pferdetaping Handbuch von Renate Ettl (Deutsch) \u2714 Vertraut werden mit den wichtigsten Anlagemethoden und Therapiem\u00f6glichkeiten mit VetkinTape\u00ae\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetkintape.com\/de\/kinesiotape-bucher-tiere\/perdetaping-handbuch\/\" \/>\n<meta property=\"og:site_name\" content=\"VetkinTape\u00ae DE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/vetkintape\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-06T08:37:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetkintape.com\/de\/wp-content\/uploads\/sites\/19\/2023\/04\/Kinesiotaping-beim-Pferd-2.-Auflage-Ettl.png\" \/>\n\t<meta property=\"og:image:width\" content=\"363\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vetkintape.com\/de\/kinesiotape-bucher-tiere\/perdetaping-handbuch\/\",\"url\":\"https:\/\/www.vetkintape.com\/de\/kinesiotape-bucher-tiere\/perdetaping-handbuch\/\",\"name\":\"Taping Handbuch f\u00fcr Pferde | VetkinTape\u00ae DE Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/www.vetkintape.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vetkintape.com\/de\/kinesiotape-bucher-tiere\/perdetaping-handbuch\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.vetkintape.com\/de\/kinesiotape-bucher-tiere\/perdetaping-handbuch\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/vetkintape.ignito.nl\/de\/wp-content\/uploads\/sites\/19\/2023\/04\/Kinesiotaping-beim-Pferd-2.-Auflage-Ettl.png\",\"datePublished\":\"2023-04-21T10:19:26+00:00\",\"dateModified\":\"2025-05-06T08:37:07+00:00\",\"description\":\"Pferdetaping Handbuch von Renate Ettl (Deutsch) \u2714 Vertraut werden mit den wichtigsten Anlagemethoden und Therapiem\u00f6glichkeiten mit VetkinTape\u00ae\",\"breadcrumb\":{\"@id\":\"https:\/\/www.vetkintape.com\/de\/kinesiotape-bucher-tiere\/perdetaping-handbuch\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vetkintape.com\/de\/kinesiotape-bucher-tiere\/perdetaping-handbuch\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.vetkintape.com\/de\/kinesiotape-bucher-tiere\/perdetaping-handbuch\/#primaryimage\",\"url\":\"https:\/\/vetkintape.ignito.nl\/de\/wp-content\/uploads\/sites\/19\/2023\/04\/Kinesiotaping-beim-Pferd-2.-Auflage-Ettl.png\",\"contentUrl\":\"https:\/\/vetkintape.ignito.nl\/de\/wp-content\/uploads\/sites\/19\/2023\/04\/Kinesiotaping-beim-Pferd-2.-Auflage-Ettl.png\",\"width\":363,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vetkintape.com\/de\/kinesiotape-bucher-tiere\/perdetaping-handbuch\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/vetkintape.ignito.nl\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/vetkintape.ignito.nl\/de\/overview\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Taping Handbuch f\u00fcr Pferde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vetkintape.com\/de\/#website\",\"url\":\"https:\/\/www.vetkintape.com\/de\/\",\"name\":\"VetkinTape\u00ae DE\",\"description\":\"Das Kinesiotape f\u00fcr Tiere\",\"publisher\":{\"@id\":\"https:\/\/www.vetkintape.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vetkintape.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.vetkintape.com\/de\/#organization\",\"name\":\"VetkinTape\u00ae\",\"url\":\"https:\/\/www.vetkintape.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.vetkintape.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.vetkintape.com\/wp-content\/uploads\/sites\/15\/2021\/02\/vetkintape-logo.svg\",\"contentUrl\":\"https:\/\/www.vetkintape.com\/wp-content\/uploads\/sites\/15\/2021\/02\/vetkintape-logo.svg\",\"width\":1773,\"height\":1030,\"caption\":\"VetkinTape\u00ae\"},\"image\":{\"@id\":\"https:\/\/www.vetkintape.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/vetkintape\/\",\"https:\/\/www.instagram.com\/vetkintape_official\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Taping Handbuch f\u00fcr Pferde | VetkinTape\u00ae DE Deutschland","description":"Pferdetaping Handbuch von Renate Ettl (Deutsch) \u2714 Vertraut werden mit den wichtigsten Anlagemethoden und Therapiem\u00f6glichkeiten mit VetkinTape\u00ae","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vetkintape.com\/de\/kinesiotape-bucher-tiere\/perdetaping-handbuch\/","og_locale":"de_DE","og_type":"article","og_title":"Taping Handbuch f\u00fcr Pferde | VetkinTape\u00ae DE Deutschland","og_description":"Pferdetaping Handbuch von Renate Ettl (Deutsch) \u2714 Vertraut werden mit den wichtigsten Anlagemethoden und Therapiem\u00f6glichkeiten mit VetkinTape\u00ae","og_url":"https:\/\/www.vetkintape.com\/de\/kinesiotape-bucher-tiere\/perdetaping-handbuch\/","og_site_name":"VetkinTape\u00ae DE","article_publisher":"https:\/\/www.facebook.com\/vetkintape\/","article_modified_time":"2025-05-06T08:37:07+00:00","og_image":[{"width":363,"height":500,"url":"https:\/\/www.vetkintape.com\/de\/wp-content\/uploads\/sites\/19\/2023\/04\/Kinesiotaping-beim-Pferd-2.-Auflage-Ettl.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetkintape.com\/de\/kinesiotape-bucher-tiere\/perdetaping-handbuch\/","url":"https:\/\/www.vetkintape.com\/de\/kinesiotape-bucher-tiere\/perdetaping-handbuch\/","name":"Taping Handbuch f\u00fcr Pferde | VetkinTape\u00ae DE Deutschland","isPartOf":{"@id":"https:\/\/www.vetkintape.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetkintape.com\/de\/kinesiotape-bucher-tiere\/perdetaping-handbuch\/#primaryimage"},"image":{"@id":"https:\/\/www.vetkintape.com\/de\/kinesiotape-bucher-tiere\/perdetaping-handbuch\/#primaryimage"},"thumbnailUrl":"https:\/\/vetkintape.ignito.nl\/de\/wp-content\/uploads\/sites\/19\/2023\/04\/Kinesiotaping-beim-Pferd-2.-Auflage-Ettl.png","datePublished":"2023-04-21T10:19:26+00:00","dateModified":"2025-05-06T08:37:07+00:00","description":"Pferdetaping Handbuch von Renate Ettl (Deutsch) \u2714 Vertraut werden mit den wichtigsten Anlagemethoden und Therapiem\u00f6glichkeiten mit VetkinTape\u00ae","breadcrumb":{"@id":"https:\/\/www.vetkintape.com\/de\/kinesiotape-bucher-tiere\/perdetaping-handbuch\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetkintape.com\/de\/kinesiotape-bucher-tiere\/perdetaping-handbuch\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.vetkintape.com\/de\/kinesiotape-bucher-tiere\/perdetaping-handbuch\/#primaryimage","url":"https:\/\/vetkintape.ignito.nl\/de\/wp-content\/uploads\/sites\/19\/2023\/04\/Kinesiotaping-beim-Pferd-2.-Auflage-Ettl.png","contentUrl":"https:\/\/vetkintape.ignito.nl\/de\/wp-content\/uploads\/sites\/19\/2023\/04\/Kinesiotaping-beim-Pferd-2.-Auflage-Ettl.png","width":363,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetkintape.com\/de\/kinesiotape-bucher-tiere\/perdetaping-handbuch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vetkintape.ignito.nl\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/vetkintape.ignito.nl\/de\/overview\/"},{"@type":"ListItem","position":3,"name":"Taping Handbuch f\u00fcr Pferde"}]},{"@type":"WebSite","@id":"https:\/\/www.vetkintape.com\/de\/#website","url":"https:\/\/www.vetkintape.com\/de\/","name":"VetkinTape\u00ae DE","description":"Das Kinesiotape f\u00fcr Tiere","publisher":{"@id":"https:\/\/www.vetkintape.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetkintape.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.vetkintape.com\/de\/#organization","name":"VetkinTape\u00ae","url":"https:\/\/www.vetkintape.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.vetkintape.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetkintape.com\/wp-content\/uploads\/sites\/15\/2021\/02\/vetkintape-logo.svg","contentUrl":"https:\/\/www.vetkintape.com\/wp-content\/uploads\/sites\/15\/2021\/02\/vetkintape-logo.svg","width":1773,"height":1030,"caption":"VetkinTape\u00ae"},"image":{"@id":"https:\/\/www.vetkintape.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/vetkintape\/","https:\/\/www.instagram.com\/vetkintape_official\/"]}]}},"_links":{"self":[{"href":"https:\/\/vetkintape.ignito.nl\/de\/wp-json\/wp\/v2\/product\/70023163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vetkintape.ignito.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vetkintape.ignito.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/vetkintape.ignito.nl\/de\/wp-json\/wp\/v2\/comments?post=70023163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vetkintape.ignito.nl\/de\/wp-json\/wp\/v2\/media\/70023165"}],"wp:attachment":[{"href":"https:\/\/vetkintape.ignito.nl\/de\/wp-json\/wp\/v2\/media?parent=70023163"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/vetkintape.ignito.nl\/de\/wp-json\/wp\/v2\/product_brand?post=70023163"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vetkintape.ignito.nl\/de\/wp-json\/wp\/v2\/product_cat?post=70023163"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vetkintape.ignito.nl\/de\/wp-json\/wp\/v2\/product_tag?post=70023163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}